{"id":541,"date":"2026-04-17T09:11:29","date_gmt":"2026-04-17T09:11:29","guid":{"rendered":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/?page_id=541"},"modified":"2026-06-30T07:52:13","modified_gmt":"2026-06-30T07:52:13","slug":"faqs","status":"publish","type":"page","link":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/faqs","title":{"rendered":"FAQ&#8217;s"},"content":{"rendered":"\r\n<section class=\"about-banner-bg position-relative\">\r\n<div class=\"container custom-container\">\r\n<div class=\"row align-items-center\">\r\n<div class=\"col-md-12\">\r\n<h1>Frequenty Asked Questions<\/h1>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>\r\n<section class=\"faqs-section container py-5\">\r\n<h2 class=\"text-center mb-4 fw-bold\">FAQs About Jeena Sikho HiiMS Clinic<\/h2>\r\n<div id=\"faqAccordion\" class=\"accordion\"><!-- Q1 -->\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq1\" class=\"accordion-header\"><button class=\"accordion-button\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse1\"> <b>Q1: Are the treatment processes followed at Jeena Sikho HiiMS Ayurveda safe and natural?<\/b> <\/button><\/h3>\r\n<div id=\"collapse1\" class=\"accordion-collapse collapse show\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Treatments are designed using traditional Ayurvedic principles under expert supervision for safe and natural healing.<\/div>\r\n<\/div>\r\n<\/div>\r\n<!-- Q2 -->\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq2\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse2\"> <b>Q2: Are there any side effects of Ayurvedic treatments?<\/b> <\/button><\/h3>\r\n<div id=\"collapse2\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Treatments are generally gentle. Any adjustments are made to suit individual health conditions.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq3\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse3\"> <b>Q3: How is Jeena Sikho HiiMS Ayurveda different from other Ayurvedic centers?<\/b> <\/button><\/h3>\r\n<div id=\"collapse3\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Jeena Sikho HiiMS combines expert doctors, personalised care, advanced Panchakarma therapies, and a well-equipped infrastucture for comprehensive wellness.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq4\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse4\"> <b>Q4: How do I get an appointment for Jeena Sikho HiiMS ?<\/b> <\/button><\/h3>\r\n<div id=\"collapse4\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Appointments can be booked online, via phone, or by visiting the clinic in person.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq5\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse5\"> <b>Q5: Can anyone of any age access treatments at Jeena Sikho HiiMS ?<\/b> <\/button><\/h3>\r\n<div id=\"collapse5\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Therapies are available for adults and children with customised care for each age group.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq6\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse6\"> <b>Q6: What is the Jeena Sikho HiiMS clinic\u2019s location address?<\/b> <\/button><\/h3>\r\n<div id=\"collapse6\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">New Market, 19-B\/2, New Rohtak Rd, near Liberty Cinema, Block 59, Karol Bagh, New Delhi, Delhi, 110005<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq7\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse7\"> <b>Q7: Are lifestyle changes required during treatment?<\/b> <\/button><\/h3>\r\n<div id=\"collapse7\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Personalised diet and lifestyle recommendations are an essential part of effective treatment.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq8\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse8\"> <b>Q8: What facilities are available at Jeena Sikho HiiMS ?<\/b> <\/button><\/h3>\r\n<div id=\"collapse8\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Jeena Sikho HiiMS provides integrated Ayurvedic therapies and Naturopathy combined with modern sciences for all kinds of chronic and lifestyle-related disorders. The center is well-equipped with all kinds of modern facilities along with trained faculty and specialised doctors.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq9\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse9\"> <b>Q9: Is there a way to get Ayurvedic treatment remotely or online at Jeena Sikho HiiMS ?<\/b> <\/button><\/h3>\r\n<div id=\"collapse9\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Online consultations are available for guidance, follow-ups, and personalised health plans.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq10\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse10\"> <b>Q10: Are the doctors at Jeena Sikho HiiMS well-experienced?<\/b> <\/button><\/h3>\r\n<div id=\"collapse10\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">The clinic has a team of experienced Ayurvedic doctors trained in traditional and modern practices.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq11\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse11\"> <b>Q11: What are the visiting hours for patients at Jeena Sikho HiiMS ?<\/b> <\/button><\/h3>\r\n<div id=\"collapse11\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Visiting hours are usually in the morning and evening; please check with reception for exact timings.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq12\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse12\"> <b>Q12: Does the clinic accept health insurance and cashless treatment?<\/b> <\/button><\/h3>\r\n<div id=\"collapse12\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Yes, Jeena Sikho HiiMS accepts insurance and provides cashless treatment options.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq13\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse13\"> <b>Q13: What payment modes are accepted at Jeena Sikho HiiMS ?<\/b> <\/button><\/h3>\r\n<div id=\"collapse13\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">The clinic accepts cash, cards, UPI, and online transfers.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq14\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse14\"> <b>Q14: How can I get copies of my medical reports and discharge summary?<\/b> <\/button><\/h3>\r\n<div id=\"collapse14\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">Reports and discharge summaries can be collected from the records department.<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"accordion-item\">\r\n<h3 id=\"faq15\" class=\"accordion-header\"><button class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse15\"> <b>Q15: What is the contact number for Jeena Sikho HiiMS ?<\/b> <\/button><\/h3>\r\n<div id=\"collapse15\" class=\"accordion-collapse collapse\" data-bs-parent=\"#faqAccordion\">\r\n<div class=\"accordion-body\">You can reach the clinic at +91-77839-77839 for appointments and inquiries.<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>\r\n<p><style>\r\n.faqs-section {<br \/>  max-width: 900px;<br \/>  margin: auto;<br \/>}<br \/>.faqs-section h2 {<br \/>  font-size: 28px;<br \/>  color: #004d40;<br \/>}<br \/>.accordion-item {<br \/>  border: none;<br \/>  margin-bottom: 10px;<br \/>  border-radius: 10px;<br \/>  overflow: hidden;<br \/>  box-shadow: 0 4px 10px rgba(0,0,0,0.08);<br \/>}<br \/>.accordion-button {<br \/>  background: #f9f9f9;<br \/>  font-weight: 600;<br \/>  font-size: 16px;<br \/>  padding: 15px 20px;<br \/>  color: #222;<br \/>}<br \/>.accordion-button:focus {<br \/>  box-shadow: none;<br \/>}<br \/>.accordion-button:not(.collapsed) {<br \/>  background: #00695c;<br \/>  color: #fff;<br \/>}<br \/>.accordion-body {<br \/>  background: #fff;<br \/>  padding: 20px;<br \/>  font-size: 15px;<br \/>  line-height: 1.6;<br \/>  color: #444;<br \/>}<br \/><\/style><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Frequenty Asked Questions FAQs About Jeena Sikho HiiMS Clinic Q1: Are the treatment processes followed at Jeena Sikho HiiMS Ayurveda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-541","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FAQs \u2013 HiiMS Ayurvedic Health Questions &amp; Answers<\/title>\n<meta name=\"description\" content=\"Find answers to common questions about treatments, therapies, and services at Jeena Sikho HiiMS Karol Bagh Delhi. Visit now or book a consultation today\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/faqs\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQs \u2013 HiiMS Ayurvedic Health Questions &amp; Answers\" \/>\n<meta property=\"og:description\" content=\"Find answers to common questions about treatments, therapies, and services at Jeena Sikho HiiMS Karol Bagh Delhi. Visit now or book a consultation today.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/faqs\" \/>\n<meta property=\"og:site_name\" content=\"Karol Bagh Delhi\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T07:52:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"FAQs \u2013 HiiMS Ayurvedic Health Questions &amp; Answers\" \/>\n<meta name=\"twitter:description\" content=\"Find answers to common questions about treatments, therapies, and services at Jeena Sikho HiiMS Karol Bagh Delhi. Visit now or book a consultation today.\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hiims.in\\\/clinic\\\/karol-bagh-delhi\\\/faqs\",\"url\":\"https:\\\/\\\/hiims.in\\\/clinic\\\/karol-bagh-delhi\\\/faqs\",\"name\":\"FAQs \u2013 HiiMS Ayurvedic Health Questions & Answers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hiims.in\\\/clinic\\\/karol-bagh-delhi\\\/#website\"},\"datePublished\":\"2026-04-17T09:11:29+00:00\",\"dateModified\":\"2026-06-30T07:52:13+00:00\",\"description\":\"Find answers to common questions about treatments, therapies, and services at Jeena Sikho HiiMS Karol Bagh Delhi. Visit now or book a consultation today\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hiims.in\\\/clinic\\\/karol-bagh-delhi\\\/faqs#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hiims.in\\\/clinic\\\/karol-bagh-delhi\\\/faqs\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hiims.in\\\/clinic\\\/karol-bagh-delhi\\\/faqs#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hiims.in\\\/clinic\\\/karol-bagh-delhi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ&#8217;s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hiims.in\\\/clinic\\\/karol-bagh-delhi\\\/#website\",\"url\":\"https:\\\/\\\/hiims.in\\\/clinic\\\/karol-bagh-delhi\\\/\",\"name\":\"Karol Bagh Delhi\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hiims.in\\\/clinic\\\/karol-bagh-delhi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FAQs \u2013 HiiMS Ayurvedic Health Questions & Answers","description":"Find answers to common questions about treatments, therapies, and services at Jeena Sikho HiiMS Karol Bagh Delhi. Visit now or book a consultation today","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/faqs","og_locale":"en_US","og_type":"article","og_title":"FAQs \u2013 HiiMS Ayurvedic Health Questions & Answers","og_description":"Find answers to common questions about treatments, therapies, and services at Jeena Sikho HiiMS Karol Bagh Delhi. Visit now or book a consultation today.","og_url":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/faqs","og_site_name":"Karol Bagh Delhi","article_modified_time":"2026-06-30T07:52:13+00:00","twitter_card":"summary_large_image","twitter_title":"FAQs \u2013 HiiMS Ayurvedic Health Questions & Answers","twitter_description":"Find answers to common questions about treatments, therapies, and services at Jeena Sikho HiiMS Karol Bagh Delhi. Visit now or book a consultation today.","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/faqs","url":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/faqs","name":"FAQs \u2013 HiiMS Ayurvedic Health Questions & Answers","isPartOf":{"@id":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/#website"},"datePublished":"2026-04-17T09:11:29+00:00","dateModified":"2026-06-30T07:52:13+00:00","description":"Find answers to common questions about treatments, therapies, and services at Jeena Sikho HiiMS Karol Bagh Delhi. Visit now or book a consultation today","breadcrumb":{"@id":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/faqs#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/faqs"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/faqs#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/"},{"@type":"ListItem","position":2,"name":"FAQ&#8217;s"}]},{"@type":"WebSite","@id":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/#website","url":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/","name":"Karol Bagh Delhi","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/wp-json\/wp\/v2\/pages\/541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/wp-json\/wp\/v2\/comments?post=541"}],"version-history":[{"count":6,"href":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/wp-json\/wp\/v2\/pages\/541\/revisions"}],"predecessor-version":[{"id":1805,"href":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/wp-json\/wp\/v2\/pages\/541\/revisions\/1805"}],"wp:attachment":[{"href":"https:\/\/hiims.in\/clinic\/karol-bagh-delhi\/wp-json\/wp\/v2\/media?parent=541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}